{"id":19113,"date":"2026-02-06T10:05:27","date_gmt":"2026-02-06T09:05:27","guid":{"rendered":"https:\/\/soniapena.com\/?post_type=product&#038;p=19113"},"modified":"2026-08-26T15:27:54","modified_gmt":"2026-08-26T13:27:54","slug":"1260066","status":"publish","type":"product","link":"https:\/\/soniapena.com\/de\/producto\/1260066\/","title":{"rendered":"1260066"},"content":{"rendered":"<p><span data-sheets-root=\"1\">Vestido largo en crep con mangas tres cuartos y detalle floral de organza aplicado de forma asim\u00e9trica . Una opci\u00f3n de car\u00e1cter para madrinas e invitadas en eventos de etiqueta.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span data-sheets-root=\"1\">Vestido Largo en Crep con Detalle Floral de Organza<\/span><\/p>\n","protected":false},"featured_media":18789,"template":"","meta":{"_joinchat":[]},"product_brand":[266],"product_cat":[276,336,343,338,337],"product_tag":[345],"plantilla-producto":[274],"class_list":["post-19113","product","type-product","status-publish","has-post-thumbnail","product_brand-casablanca","product_cat-vestido-largo-manga-larga-casablanca","product_cat-bodas","product_cat-fiestas","product_cat-invitada-de-dia","product_cat-madrina-de-boda","product_tag-casablanca","plantilla-producto-casablanca","first","outofstock","product-type-variable"],"_links":{"self":[{"href":"https:\/\/soniapena.com\/de\/wp-json\/wp\/v2\/product\/19113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soniapena.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/soniapena.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soniapena.com\/de\/wp-json\/wp\/v2\/media\/18789"}],"wp:attachment":[{"href":"https:\/\/soniapena.com\/de\/wp-json\/wp\/v2\/media?parent=19113"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/soniapena.com\/de\/wp-json\/wp\/v2\/product_brand?post=19113"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/soniapena.com\/de\/wp-json\/wp\/v2\/product_cat?post=19113"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/soniapena.com\/de\/wp-json\/wp\/v2\/product_tag?post=19113"},{"taxonomy":"plantilla-producto","embeddable":true,"href":"https:\/\/soniapena.com\/de\/wp-json\/wp\/v2\/plantilla-producto?post=19113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}