{"id":19557,"date":"2026-02-12T10:23:21","date_gmt":"2026-02-12T09:23:21","guid":{"rendered":"https:\/\/soniapena.com\/?post_type=product&#038;p=19557"},"modified":"2026-08-28T09:27:28","modified_gmt":"2026-08-28T07:27:28","slug":"1260067","status":"publish","type":"product","link":"https:\/\/soniapena.com\/de\/producto\/1260067\/","title":{"rendered":"1260067"},"content":{"rendered":"<p><span data-sheets-root=\"1\">Vestido largo en crep con escote en pico, mangas tres cuartos de organza y detalle floral aplicado de forma asim\u00e9trica. Una propuesta sofisticada para madrinas e invitadas que buscan un vestido largo con volumen controlado.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span data-sheets-root=\"1\">Vestido Largo en Crep con Escote en Pico y Detalle Floral<\/span><\/p>\n","protected":false},"featured_media":14771,"template":"","meta":{"_joinchat":[]},"product_brand":[266],"product_cat":[276,336,343,338,339,337],"product_tag":[345],"plantilla-producto":[274],"class_list":["post-19557","product","type-product","status-publish","has-post-thumbnail","product_brand-casablanca","product_cat-vestido-largo-manga-larga-casablanca","product_cat-bodas","product_cat-fiestas","product_cat-invitada-de-dia","product_cat-invitada-de-noche","product_cat-madrina-de-boda","product_tag-casablanca","plantilla-producto-casablanca","first","outofstock","sale","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/soniapena.com\/de\/wp-json\/wp\/v2\/product\/19557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soniapena.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/soniapena.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soniapena.com\/de\/wp-json\/wp\/v2\/media\/14771"}],"wp:attachment":[{"href":"https:\/\/soniapena.com\/de\/wp-json\/wp\/v2\/media?parent=19557"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/soniapena.com\/de\/wp-json\/wp\/v2\/product_brand?post=19557"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/soniapena.com\/de\/wp-json\/wp\/v2\/product_cat?post=19557"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/soniapena.com\/de\/wp-json\/wp\/v2\/product_tag?post=19557"},{"taxonomy":"plantilla-producto","embeddable":true,"href":"https:\/\/soniapena.com\/de\/wp-json\/wp\/v2\/plantilla-producto?post=19557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}