{"id":15318,"date":"2026-01-19T12:03:06","date_gmt":"2026-01-19T11:03:06","guid":{"rendered":"https:\/\/soniapena.com\/?post_type=product&#038;p=15318"},"modified":"2026-09-02T11:50:58","modified_gmt":"2026-09-02T09:50:58","slug":"1260058","status":"publish","type":"product","link":"https:\/\/soniapena.com\/en\/producto\/1260058\/","title":{"rendered":"1260058"},"content":{"rendered":"<p><span data-sheets-root=\"1\">Conjunto de caft\u00e1n y pantal\u00f3n en crep confort. El caft\u00e1n presenta escote cruzado, cintur\u00f3n y mangas amplias con aberturas, combinado con pantal\u00f3n recto. Una opci\u00f3n fluida para madrinas e invitadas que prefieren una silueta c\u00f3moda en ceremonias de d\u00eda.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span data-sheets-root=\"1\">Conjunto de Caft\u00e1n y Pantal\u00f3n en Crep Confort<\/span><\/p>\n","protected":false},"featured_media":15454,"template":"","meta":{"_joinchat":[]},"product_brand":[266],"product_cat":[275,341,336,338,337],"product_tag":[345],"plantilla-producto":[299],"class_list":["post-15318","product","type-product","status-publish","has-post-thumbnail","product_brand-casablanca","product_cat-vestido-midi-manga-larga-casablanca","product_cat-bautizos-comuniones","product_cat-bodas","product_cat-invitada-de-dia","product_cat-madrina-de-boda","product_tag-casablanca","plantilla-producto-casablanca-colores","first","instock","sale","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/product\/15318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/media\/15454"}],"wp:attachment":[{"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/media?parent=15318"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/product_brand?post=15318"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/product_cat?post=15318"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/product_tag?post=15318"},{"taxonomy":"plantilla-producto","embeddable":true,"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/plantilla-producto?post=15318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}