{"id":15325,"date":"2026-01-19T12:04:54","date_gmt":"2026-01-19T11:04:54","guid":{"rendered":"https:\/\/soniapena.com\/?post_type=product&#038;p=15325"},"modified":"2026-09-01T15:56:20","modified_gmt":"2026-09-01T13:56:20","slug":"1260070","status":"publish","type":"product","link":"https:\/\/soniapena.com\/en\/producto\/1260070\/","title":{"rendered":"1260070"},"content":{"rendered":"<p><span data-sheets-root=\"1\">Vestido largo en crep confort con escote limpio, frunce lateral que realza la cintura y mangas tres cuartos con delicado detalle de plumas. Un dise\u00f1o de presencia para madrinas de boda y ceremonias de etiqueta.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span data-sheets-root=\"1\">Vestido Largo en Crep Confort con Detalle de Plumas<\/span><\/p>\n","protected":false},"featured_media":15349,"template":"","meta":{"_joinchat":[]},"product_brand":[266],"product_cat":[276,336,340,343,338,339],"product_tag":[345],"plantilla-producto":[274],"class_list":["post-15325","product","type-product","status-publish","has-post-thumbnail","product_brand-casablanca","product_cat-vestido-largo-manga-larga-casablanca","product_cat-bodas","product_cat-dama-de-honor","product_cat-fiestas","product_cat-invitada-de-dia","product_cat-invitada-de-noche","product_tag-casablanca","plantilla-producto-casablanca","first","instock","sale","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/product\/15325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/media\/15349"}],"wp:attachment":[{"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/media?parent=15325"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/product_brand?post=15325"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/product_cat?post=15325"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/product_tag?post=15325"},{"taxonomy":"plantilla-producto","embeddable":true,"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/plantilla-producto?post=15325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}