{"id":19107,"date":"2026-02-06T10:02:33","date_gmt":"2026-02-06T09:02:33","guid":{"rendered":"https:\/\/soniapena.com\/?post_type=product&#038;p=19107"},"modified":"2026-08-26T15:27:55","modified_gmt":"2026-08-26T13:27:55","slug":"1260008a","status":"publish","type":"product","link":"https:\/\/soniapena.com\/en\/producto\/1260008a\/","title":{"rendered":"1260008A"},"content":{"rendered":"<p><span data-sheets-root=\"1\">Vestido largo de fiesta confeccionado en gasa fluida, con escote asim\u00e9trico y cintura realzada mediante detalle joya. Una propuesta elegante para madrinas, damas de honor o invitadas que buscan un dise\u00f1o ligero con presencia.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span data-sheets-root=\"1\">Vestido Largo de Gasa con Escote Asim\u00e9trico<\/span><\/p>\n","protected":false},"featured_media":18543,"template":"","meta":{"_joinchat":[]},"product_brand":[266],"product_cat":[276,336,340,343,338,339,337],"product_tag":[345],"plantilla-producto":[274],"class_list":["post-19107","product","type-product","status-publish","has-post-thumbnail","product_brand-casablanca","product_cat-vestido-largo-manga-larga-casablanca","product_cat-bodas","product_cat-dama-de-honor","product_cat-fiestas","product_cat-invitada-de-dia","product_cat-invitada-de-noche","product_cat-madrina-de-boda","product_tag-casablanca","plantilla-producto-casablanca","first","instock","product-type-variable"],"_links":{"self":[{"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/product\/19107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/media\/18543"}],"wp:attachment":[{"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/media?parent=19107"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/product_brand?post=19107"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/product_cat?post=19107"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/product_tag?post=19107"},{"taxonomy":"plantilla-producto","embeddable":true,"href":"https:\/\/soniapena.com\/en\/wp-json\/wp\/v2\/plantilla-producto?post=19107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}