{"id":15206,"date":"2026-01-19T11:45:00","date_gmt":"2026-01-19T10:45:00","guid":{"rendered":"https:\/\/soniapena.com\/?post_type=product&#038;p=15206"},"modified":"2026-09-01T15:54:49","modified_gmt":"2026-09-01T13:54:49","slug":"1260022","status":"publish","type":"product","link":"https:\/\/soniapena.com\/pt-pt\/producto\/1260022\/","title":{"rendered":"1260022"},"content":{"rendered":"<p><span data-sheets-root=\"1\">Conjunto de top y pantal\u00f3n en crep confort. El top presenta escote barco, peplum asim\u00e9trico y cintur\u00f3n con hebilla, coordinado con un pantal\u00f3n de corte recto. Un look de dos piezas para eventos de d\u00eda, fiestas y ceremonias familiares.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span data-sheets-root=\"1\">Conjunto de Top y Pantal\u00f3n en Crep Confort<\/span><\/p>\n","protected":false},"featured_media":15441,"template":"","meta":{"_joinchat":[]},"product_brand":[266],"product_cat":[277,341,336,343,338],"product_tag":[345],"plantilla-producto":[299],"class_list":["post-15206","product","type-product","status-publish","has-post-thumbnail","product_brand-casablanca","product_cat-conjunto-pantalon-casablanca","product_cat-bautizos-y-comuniones","product_cat-bodas","product_cat-fiestas","product_cat-invitada-de-dia","product_tag-casablanca","plantilla-producto-casablanca-colores","first","instock","sale","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/soniapena.com\/pt-pt\/wp-json\/wp\/v2\/product\/15206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soniapena.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/soniapena.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soniapena.com\/pt-pt\/wp-json\/wp\/v2\/media\/15441"}],"wp:attachment":[{"href":"https:\/\/soniapena.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=15206"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/soniapena.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=15206"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/soniapena.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=15206"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/soniapena.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=15206"},{"taxonomy":"plantilla-producto","embeddable":true,"href":"https:\/\/soniapena.com\/pt-pt\/wp-json\/wp\/v2\/plantilla-producto?post=15206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}